{"id":4,"count":2,"description":"","link":"https:\/\/magfira.jurnal6a.my.id\/index.php\/category\/musik\/","name":"Musik","slug":"musik","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/magfira.jurnal6a.my.id\/index.php\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magfira.jurnal6a.my.id\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/magfira.jurnal6a.my.id\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/magfira.jurnal6a.my.id\/index.php\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}